{"id":1199,"date":"2019-06-18T14:47:01","date_gmt":"2019-06-18T14:47:01","guid":{"rendered":"http:\/\/antoniamarques.pt\/blog\/?p=1199"},"modified":"2019-06-18T14:50:05","modified_gmt":"2019-06-18T14:50:05","slug":"leopoldo-ii-antwerpse-handjes","status":"publish","type":"post","link":"https:\/\/antoniamarques.pt\/blog\/2019\/06\/18\/leopoldo-ii-antwerpse-handjes\/","title":{"rendered":"LEOPOLDO II E AS AMPUTA\u00c7\u00d5ES DE CHOCOLATE"},"content":{"rendered":"<p>Leopoldo II, Rei da B\u00e9lgica entre 1865 e 1909, foi respons\u00e1vel por um tremendo genoc\u00eddio no Congo, onde ter\u00e1 morto mais de 10 milh\u00f5es de pessoas!<br \/>\nUm dos crimes mais hediondos que praticou foi a amputa\u00e7\u00e3o sistem\u00e1tica de m\u00e3os, \u00e0 qual submetia os homens, mulheres e seus filhos, todos convertidos em escravos, ao servi\u00e7o da B\u00e9lgica!<br \/>\nA monstruosidade do comportamento de Leopoldo n\u00e3o \u00e9 assunto que interesse \u00e0 Europa Branca <em>main stream<\/em> divulgar, pois poderiam colocar-se a n\u00fa as estruturas nojentas, sob as quais assenta a edifica\u00e7\u00e3o do capitalismo \u00e0 europeu!<br \/>\nEste silenciamento \u00e9 estrat\u00e9gico, fundamental para que as inst\u00e2ncias de poder possam dar continuidade aos seus impiedosos e maquiav\u00e9licos projectos de desenvolvimento, ainda que para tal tenham de esconder as mortes que acumulam no curr\u00edculo!<br \/>\nEsta dilui\u00e7\u00e3o estrat\u00e9gica de mem\u00f3rias \u00e9 tr\u00e1gica, s\u00f3 ela poder\u00e1 justificar que a cidade de Antu\u00e9rpia apresente como doce t\u00edpico regional as m\u00e3os de chocolate!<br \/>\nO caos social, em que nos encontramos mergulhados, n\u00e3o \u00e9 obra do acaso, bem pelo contr\u00e1rio, \u00e9 uma pe\u00e7a de teatro tr\u00e1gico, repleto de figurantes resignados, aos quais foi amputada a vontade de querer saber a verdade!<\/p>\n<p>6 de janeiro, 2018<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leopoldo II, Rei da B\u00e9lgica entre 1865 e 1909, foi respons\u00e1vel por um tremendo genoc\u00eddio no Congo, onde ter\u00e1 morto mais de 10 milh\u00f5es de pessoas! Um dos crimes mais hediondos que praticou foi a amputa\u00e7\u00e3o sistem\u00e1tica de m\u00e3os, \u00e0 qual submetia os homens, mulheres e seus filhos, todos convertidos em escravos, ao servi\u00e7o da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1200,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/posts\/1199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/comments?post=1199"}],"version-history":[{"count":4,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/posts\/1199\/revisions"}],"predecessor-version":[{"id":1204,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/posts\/1199\/revisions\/1204"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/media\/1200"}],"wp:attachment":[{"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/media?parent=1199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/categories?post=1199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/tags?post=1199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}