{"id":1536,"date":"2019-12-24T00:26:37","date_gmt":"2019-12-24T00:26:37","guid":{"rendered":"http:\/\/antoniamarques.pt\/blog\/?p=1536"},"modified":"2020-05-31T16:05:11","modified_gmt":"2020-05-31T16:05:11","slug":"a-criacao-partilhada","status":"publish","type":"post","link":"https:\/\/antoniamarques.pt\/blog\/2019\/12\/24\/a-criacao-partilhada\/","title":{"rendered":"a cria\u00e7\u00e3o partilhada"},"content":{"rendered":"<p style=\"text-align: center;\">Os instantes de cria\u00e7\u00e3o partilhada, \u00a0<em>graves<\/em>, <em>largos<\/em>, <em>moderatos<\/em>, <em>allegros<\/em> ou <em>prestissimos<\/em>\u00a0contribuem para a cria\u00e7\u00e3o de linhas mel\u00f3dicas que d\u00e3o sentido ao tempo. Orientar a sua elabora\u00e7\u00e3o \u00e9 um privil\u00e9gio!<\/p>\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<\/div>\n<p style=\"text-align: center;\">Iluminar os processos criativos, experimentar metodologias de trabalho alternativas, agir e criar em prol dos valores e humanismo que a sensibilidade transporta, s\u00e3o objetivos centrais das in\u00fameras sess\u00f5es onde decorre a cria\u00e7\u00e3o art\u00edstica partilhada!<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1540 size-large\" src=\"https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-12-23-\u00e0s-23.55.52-1024x294.png\" alt=\"\" width=\"640\" height=\"184\" srcset=\"https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-12-23-\u00e0s-23.55.52-1024x294.png 1024w, https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-12-23-\u00e0s-23.55.52-300x86.png 300w, https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-12-23-\u00e0s-23.55.52-768x220.png 768w, https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-12-23-\u00e0s-23.55.52.png 1348w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: center;\">LIVROS DE PROJETO\u00a0[di\u00e1rio de artista revisitado]<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1548 size-full\" src=\"https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/livros-1.jpg\" alt=\"\" width=\"765\" height=\"914\" srcset=\"https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/livros-1.jpg 765w, https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/livros-1-251x300.jpg 251w\" sizes=\"auto, (max-width: 765px) 100vw, 765px\" \/><\/p>\n<div class=\"page\" title=\"Page 1\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>A cria\u00e7\u00e3o partilhada em contexto de forma\u00e7\u00e3o\u00a0(Esc. Sec. Gon\u00e7alves Zarco, em hor\u00e1rio tardio)<\/p>\n<p>Este curso proporcionou aos formandos a cria\u00e7\u00e3o de um Livro de Projeto, atrav\u00e9s da explora\u00e7\u00e3o e experimenta\u00e7\u00e3o de fundamentais linguagens de express\u00e3o pl\u00e1stica e comunica\u00e7\u00e3o visual. As din\u00e2micas operativas a empreendidas foram delineadas para incrementar as compet\u00eancias criativas dos docentes, pelo que se apresentaram como uma possibilidade metodol\u00f3gica a aplicar e desenvolver em contexto de sala de aula. O percurso formativo, fundado numa s\u00f3lida perspetiva hist\u00f3rica, fundou-se numa revisita\u00e7\u00e3o orientada ao fascinante mundo dos di\u00e1rios de artista, \u00a0proporcionando aos formandos uma ampla e transversal compreens\u00e3o da especial relev\u00e2ncia de que se revestem os Di\u00e1rios de Artista, analisando e refletindo a partir dos processos de trabalho, utilizados por criativos em \u00e1reas t\u00e3o distintas como a M\u00fasica, Arquitetura, Design, Artes Pl\u00e1sticas, entre outras.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p style=\"text-align: center;\">ARTE NA ESCOLA &#8211; OFICINAS DE CRIA\u00c7\u00c3O ITINERANTE<br \/>\nEduca\u00e7\u00e3o Art\u00edstica &#8211; forma\u00e7\u00e3o essencial para ler, ouvir, sentir e transformar o mundo<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1542 size-large\" src=\"https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-12-24-\u00e0s-00.10.54-858x1024.png\" alt=\"\" width=\"640\" height=\"764\" srcset=\"https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-12-24-\u00e0s-00.10.54-858x1024.png 858w, https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-12-24-\u00e0s-00.10.54-251x300.png 251w, https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-12-24-\u00e0s-00.10.54-768x916.png 768w, https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-12-24-\u00e0s-00.10.54.png 989w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p style=\"text-align: center;\">a cria\u00e7\u00e3o partilhada em contexto educativo (Escola T\u00e9cnica do Mindelo)<\/p>\n<p>[em elabora\u00e7\u00e3o]<\/p>\n<\/div>\n<div class=\"column\">\n<p style=\"text-align: center;\">P\u00c9 NA TXON<br \/>\n[em tr\u00e2nsito, pela cria\u00e7\u00e3o de lugares indisciplinados]<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1544 aligncenter\" src=\"https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-12-24-\u00e0s-00.16.24.jpg\" alt=\"\" width=\"914\" height=\"933\" srcset=\"https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-12-24-\u00e0s-00.16.24.jpg 914w, https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-12-24-\u00e0s-00.16.24-294x300.jpg 294w, https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-12-24-\u00e0s-00.16.24-768x784.jpg 768w\" sizes=\"auto, (max-width: 914px) 100vw, 914px\" \/><\/p>\n<p style=\"text-align: center;\">a cria\u00e7\u00e3o partilhada em contexto oficinal (Centro Cultural de Mindelo)<\/p>\n<p>Partilhar os processos criativos e as metodologias de trabalho em artes visuais, capazes de despoletar a interven\u00e7\u00e3o e participa\u00e7\u00e3o c\u00edvica, bem como a defesa dos valores e humanismo que a sensibilidade transporta, foi o objetivo central desta oficina!<\/p>\n<p>Este Workshop, pensado para promover abordagens espaciais partilhadas, centrou-se na experimenta\u00e7\u00e3o de uma metodologia, onde se encontram a t\u00e9cnica da <b>deriva<\/b>, enquadrada no m\u00e9todo <b>psicogeogr\u00e1fico<\/b>, o processo da <b>cartografia da a\u00e7\u00e3o social <\/b>e a dimens\u00e3o do <i>Caminhar <\/i>como pr\u00e1tica est\u00e9tica, no sentido de Vaguear na <i>Deriva <\/i>para <i>Mapear <\/i>um conjunto de Sensa\u00e7\u00f5es Est\u00e9ticas.<\/p>\n<p>O conjunto de sess\u00f5es viabilizou o desenvolvimento de projetos pontuais de car\u00e1ter experimental, estimulando\u00a0a valoriza\u00e7\u00e3o dos processos e dos procedimentos de trabalho com diferentes meios e materiais, pelo que os momentos de partilha e socializa\u00e7\u00e3o dos conhecimentos progressivamente adquiridos foram fundamentais.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><span class=\"Apple-converted-space\">\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1578\" src=\"https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-07-19-\u00e0s-00.57.35-c\u00f3pia.jpg\" alt=\"\" width=\"1113\" height=\"592\" srcset=\"https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-07-19-\u00e0s-00.57.35-c\u00f3pia.jpg 1113w, https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-07-19-\u00e0s-00.57.35-c\u00f3pia-300x160.jpg 300w, https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-07-19-\u00e0s-00.57.35-c\u00f3pia-768x408.jpg 768w, https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-07-19-\u00e0s-00.57.35-c\u00f3pia-1024x545.jpg 1024w\" sizes=\"auto, (max-width: 1113px) 100vw, 1113px\" \/> <\/span><\/p>\n<p><span class=\"Apple-converted-space\">\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1580\" src=\"https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-07-19-\u00e0s-00.40.26-c\u00f3pia-2.jpg\" alt=\"\" width=\"1575\" height=\"978\" srcset=\"https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-07-19-\u00e0s-00.40.26-c\u00f3pia-2.jpg 1575w, https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-07-19-\u00e0s-00.40.26-c\u00f3pia-2-300x186.jpg 300w, https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-07-19-\u00e0s-00.40.26-c\u00f3pia-2-768x477.jpg 768w, https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-07-19-\u00e0s-00.40.26-c\u00f3pia-2-1024x636.jpg 1024w\" sizes=\"auto, (max-width: 1575px) 100vw, 1575px\" \/><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1577\" src=\"https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-07-18-\u00e0s-14.32.58-c\u00f3pia.jpg\" alt=\"\" width=\"1432\" height=\"531\" srcset=\"https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-07-18-\u00e0s-14.32.58-c\u00f3pia.jpg 1432w, https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-07-18-\u00e0s-14.32.58-c\u00f3pia-300x111.jpg 300w, https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-07-18-\u00e0s-14.32.58-c\u00f3pia-768x285.jpg 768w, https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-07-18-\u00e0s-14.32.58-c\u00f3pia-1024x380.jpg 1024w\" sizes=\"auto, (max-width: 1432px) 100vw, 1432px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1579\" src=\"https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-07-18-\u00e0s-19.45.51.jpg\" alt=\"\" width=\"1059\" height=\"623\" srcset=\"https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-07-18-\u00e0s-19.45.51.jpg 1059w, https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-07-18-\u00e0s-19.45.51-300x176.jpg 300w, https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-07-18-\u00e0s-19.45.51-768x452.jpg 768w, https:\/\/antoniamarques.pt\/blog\/wp-content\/uploads\/2019\/12\/Captura-de-ecr\u00e3-2019-07-18-\u00e0s-19.45.51-1024x602.jpg 1024w\" sizes=\"auto, (max-width: 1059px) 100vw, 1059px\" \/><\/p>\n<p>[em elabora\u00e7\u00e3o]<\/p>\n<p>Ant\u00f3nia Marques<br \/>\n2019<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os instantes de cria\u00e7\u00e3o partilhada, \u00a0graves, largos, moderatos, allegros ou prestissimos\u00a0contribuem para a cria\u00e7\u00e3o de linhas mel\u00f3dicas que d\u00e3o sentido ao tempo. Orientar a sua elabora\u00e7\u00e3o \u00e9 um privil\u00e9gio! Iluminar os processos criativos, experimentar metodologias de trabalho alternativas, agir e criar em prol dos valores e humanismo que a sensibilidade transporta, s\u00e3o objetivos centrais das [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1576,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1536","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/posts\/1536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/comments?post=1536"}],"version-history":[{"count":30,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/posts\/1536\/revisions"}],"predecessor-version":[{"id":1950,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/posts\/1536\/revisions\/1950"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/media\/1576"}],"wp:attachment":[{"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/media?parent=1536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/categories?post=1536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/tags?post=1536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}