{"id":3561,"date":"2024-01-29T01:05:00","date_gmt":"2024-01-29T01:05:00","guid":{"rendered":"http:\/\/antoniamarques.pt\/blog\/?p=3561"},"modified":"2024-01-29T21:43:17","modified_gmt":"2024-01-29T21:43:17","slug":"o-estado-de-decadencia","status":"publish","type":"post","link":"https:\/\/antoniamarques.pt\/blog\/2024\/01\/29\/o-estado-de-decadencia\/","title":{"rendered":"ESTADO DE DECAD\u00caNCIA"},"content":{"rendered":"\n<p>Almas g\u00e9meas!&nbsp;<\/p>\n\n\n\n<p>O impacto, provocado pela horrenda novela de vers\u00f5es e alocu\u00e7\u00f5es, a que a revela\u00e7\u00e3o do \u201ccaso das g\u00e9meas\u201d deu azo, ter\u00e1 toldado a compreens\u00e3o da gravidade dos factos que a todos envolve! Por\u00e9m, em nome do tanto e de tantos que, sob a batuta de uma equipa ministerial, pereceram no decurso da travessia da longa e angustiante pandemia, urge refletir sobre a decad\u00eancia que presidiu o Estado de emerg\u00eancia!<\/p>\n\n\n\n<p>No sentido de estabelecer a liga\u00e7\u00e3o temporal, que os intervenientes medi\u00e1ticos dispensaram, a narrativa sucede articulando o tempo dos eventos pol\u00edticos com o vertiginoso ritmo, imposto pelo rel\u00f3gio pand\u00e9mico.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Coliga\u00e7\u00e3o Zero<\/strong><\/li>\n<\/ol>\n\n\n\n<p><em><strong>A eclos\u00e3o da \u201ccoliga\u00e7\u00e3o zero\u201d, na democracia portuguesa, \u00e9 ainda um mist\u00e9rio e continua a ser objeto de estudo de alguns cidad\u00e3os inconformados. Pesquisadores e ativistas em nome individual, t\u00eam encontrado ind\u00edcios da contamina\u00e7\u00e3o em amostras sociais diversas, coletadas semanas antes da surgimento da doen\u00e7a na Assembleia da Rep\u00fablica, no final de 2015.<\/strong><\/em><\/p>\n\n\n\n<p>Sob a \u00e9gide da estabilidade e da supera\u00e7\u00e3o dos traumas provocados pela austeridade, em 2015 o parlamento foi sujeito a uma inesperada deriva! Somando votos e cumplicidades \u00e0 esquerda, o partido socialista, apesar de n\u00e3o ter ganho as elei\u00e7\u00f5es, venceu a hist\u00f3ria das coliga\u00e7\u00f5es e assumiu o comando das opera\u00e7\u00f5es legislativas. Da parlamentar ala sinistra emergiu um surpreendente triunvirato, liderado por Ant\u00f3nio Costa, que haveria de conduzir o pa\u00eds \u00e0 presente confrangedora distopia!&nbsp;<\/p>\n\n\n\n<p>Com as tormentas de S\u00f3crates e Jos\u00e9 Seguro boiando sobre \u00e1guas passadas, usufruindo de in\u00e9ditas condi\u00e7\u00f5es de governabilidade, Ant\u00f3nio Costa, aproveitou a bonan\u00e7a e fez-se ao mar, navegando \u00e0 bolina de um parlamento rendido. Da ala esquerda, ao flanco da direita, atravessando o centro, nem ondas gigantes no horizonte, nem ventanias desordeiras no firmamento, na assembleia da rep\u00fablica, entretanto convertida em est\u00e2ncia termal da democracia, tudo serenou e a ruinosa governan\u00e7a socialista triunfou!<\/p>\n\n\n\n<p><strong>2. Per\u00edodo de Incuba\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p><em><strong>Ter\u00e1 sido breve, e de enorme gravidade, o intervalo de tempo que sucedeu entre a exposi\u00e7\u00e3o aos agentes patog\u00e9nicos e a manifesta\u00e7\u00e3o das primeiras consequ\u00eancias. O per\u00edodo de incuba\u00e7\u00e3o, da sinistra coliga\u00e7\u00e3o, teve lugar dentro das c\u00e9lulas partid\u00e1rias e, num \u00e1pice, estendeu-se de forma descontrolada amea\u00e7ando a popula\u00e7\u00e3o.<\/strong><\/em><\/p>\n\n\n\n<p>Investido e apoiado pela anu\u00eancia e cumplicidade dos partidos \u00e0 esquerda, o novo primeiro-ministro n\u00e3o perdeu tempo, arregimentou as suas tropas, convidou os amigos, reuniu a fam\u00edlia e voltou a fazer planos! <a href=\"https:\/\/antoniamarques.pt\/blog\/2022\/05\/20\/democracia-entre-burros-e-ferraris\/\">Astuto e habituado <\/a>a sabotar as regras do jogo, rapidamente atirou borda-fora os acordos de circunst\u00e2ncia e, impiedosamente avan\u00e7ou, focado na conquista de um lugar cimeiro entre as lideran\u00e7as do mundo neo-liberalizado. Sem olhar a meios, arrastou tudo e todos na prossecu\u00e7\u00e3o da sua mesquinha ambi\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p>Perseguindo os seus objetivos pessoais, o l\u00edder da governan\u00e7a socialista cumpriu, sem clem\u00eancia, o ruinoso programa de neg\u00f3cios definido pela usura da Comiss\u00e3o Europeia. A generalidade da popula\u00e7\u00e3o, ainda a bra\u00e7os com os despojos da troika, viu-se assim de novo envolvida numa insidiosa vaga de assaltos e atentados \u00e0s suas j\u00e1 t\u00e3o prec\u00e1rias condi\u00e7\u00f5es de vida!&nbsp;<\/p>\n\n\n\n<p>Essa empreitada voraz, longa e excruciante, sustentada pelos parceiros do triunvirato muito para al\u00e9m dos limites da razoabilidade, agudizou indecentemente as assimetrias sociais, fazendo aumentar de forma indecorosa o n\u00famero de homens e mulheres em situa\u00e7\u00e3o de emerg\u00eancia, em virtude de terem sido desapossados dos lucros da sua for\u00e7a de trabalho, entretanto desviados para as aventuras capitalistas dos amigos do primeiro-ministro.<\/p>\n\n\n\n<p><strong>3. Transmiss\u00e3o comunit\u00e1ria<\/strong><\/p>\n\n\n\n<p><em><strong>Ap\u00f3s um per\u00edodo de incuba\u00e7\u00e3o, que a (quase) todos deixou perplexo, o cont\u00e1gio de indiv\u00edduos pela maleita sinistra, tomou conta da Assembleia da Rep\u00fablica.&nbsp;No dia 26 de novembro, ante a possibilidade da contamina\u00e7\u00e3o extravasar o hemiciclo, foi declarado o estado de transmiss\u00e3o comunit\u00e1ria da maleita socialista.<\/strong><\/em><\/p>\n\n\n\n<p>Ant\u00f3nio Costa, conhecido por, em benef\u00edcio pr\u00f3prio, arrasar tudo por onde passa, aproveitou a estabilidade que lhe foi concedida para terraplanar as condi\u00e7\u00f5es de vida da generalidade dos portugueses! Sob a sua batuta cresceram exponencialmente as fam\u00edlias sem abrigo, os sal\u00e1rios minguados, os pobres, os indigentes sem rendimentos para aviar medicamentos, os utentes sem m\u00e9dico, os m\u00e9dicos sem tempo para as suas fam\u00edlias, as barracas para alojar por tempo indeterminado trabalhadores migrantes, a precariedade, as rupturas, os alojamentos especulados, os despejos, os abusos dos arrendat\u00e1rios, os vistos de ouro para captar milion\u00e1rios, os atestados de cidadania para parceiros de neg\u00f3cios, os apoios sem fundo para projetos sem rumo, os ajustes diretos para favorecer o empreendedorismo dos amigos, \u2026 &nbsp;<\/p>\n\n\n\n<p>Longa e desesperante a lista dos improp\u00e9rios lan\u00e7ados \u00e0 lusa terra_planada por Costa, enquanto na est\u00e2ncia termal, vulgo assembleia da rep\u00fablica, imperava a cumplicidade <em>in extremis<\/em> com os devaneios do triunvirato e uma insuport\u00e1vel aus\u00eancia de como\u00e7\u00e3o!<\/p>\n\n\n\n<p><strong>4. Transmiss\u00e3o Local<\/strong><\/p>\n\n\n\n<p><em><strong>Enquanto a generalidade da popula\u00e7\u00e3o, entretanto atingida, aprendia a lidar com as consequ\u00eancias da enfermidade socialista, nas institui\u00e7\u00f5es do Estado as patologias circulavam sem restri\u00e7\u00f5es, acelerando a transmiss\u00e3o dos malef\u00edcios um pouco por todo o lado!<\/strong><\/em><\/p>\n\n\n\n<p>Perante a amplia\u00e7\u00e3o da desgra\u00e7a com que fomos brindados, ficou claro e bem esclarecido que a estabilidade governativa, a ter servido algu\u00e9m, n\u00e3o ter\u00e1 certamente servido a generalidade da popula\u00e7\u00e3o, amplamente desprezada pelo Estado, que sobrevive \u00e0 conta de sacrif\u00edcios e ex\u00edguos sal\u00e1rios. Pois, ainda que, de facto, o tempo fosse de extrema emerg\u00eancia social a t\u00e3o almejada estabilidade serviu apenas para viabilizar a <a href=\"https:\/\/antoniamarques.pt\/blog\/2022\/05\/24\/governancas-absolutas\/\">conduta abusiva da governan\u00e7a socialista<\/a>, que se apropriou do Estado e o converteu num decadente antro de neg\u00f3cios familiares, consagrado quase em exclusivo ao tr\u00e1fico de influ\u00eancias e \u00e0 pr\u00e1tica de atividades il\u00edcitas.\u00a0<\/p>\n\n\n\n<p>S\u00e3o detest\u00e1veis o dolo e a deprava\u00e7\u00e3o resultantes da prom\u00edscua atribui\u00e7\u00e3o de cargos de relev\u00e2ncia governativa, em fun\u00e7\u00e3o dos la\u00e7os de sangue e dos apelidos de fam\u00edlia.<\/p>\n\n\n\n<p>Enteados ileg\u00edtimos, primos bastardos, tios emprestados, amigos do peito, cunhados de secret\u00e1rios, filhos de assessores, consultores afilhados, padrinhos de circunst\u00e2ncia, maridos, esposas madrastas sem pasta, pastas sem t\u00edtulos para entregar aos padrastos. \u00c9 catastr\u00f3fica a rede de consanguinidade que Costa urdiu em torno das institui\u00e7\u00f5es da Rep\u00fablica Portuguesa, com a anu\u00eancia e cumplicidade das restantes figuras de Estado.<\/p>\n\n\n\n<p><strong>5. Distanciamento Social&nbsp;<\/strong><\/p>\n\n\n\n<p><em><strong>No final de 2019, ap\u00f3s um per\u00edodo de transmiss\u00e3o descontrolada, a maleita socialista entrou numa fase mais aguda, condicionando e limitando o acesso das pessoas aos servi\u00e7os p\u00fablicos de sa\u00fade. Em virtude do isolamento for\u00e7ado, muitos utentes viram as suas debilidades seriamente agravadas! <\/strong><\/em><\/p>\n\n\n\n<p>Marcelo, Presidente Rebelo de Sousa, apadrinhou o florescimento desses amplos ramos familiares. Aficcionado por manobras de distra\u00e7\u00e3o e cerim\u00f3nias exclusivas, frequentou assiduamente os sumptuosos festins da governan\u00e7a socialista. Usufruiu de banquetes extra_ordin\u00e1rios, divertiu-se com os enredos, as birras e os caprichos dos bobos da corte de Costa, apreciou as cantilenas, alinhou nos esquemas e bailaricos da maioria e promulgou, sempre, a ribaldaria governativa.&nbsp;<\/p>\n\n\n\n<p>De permeio, entre uma e outra recrea\u00e7\u00e3o, Rebelo de Sousa, dedicado promotor dos fandangos da pr\u00f3pria fam\u00edlia, ter\u00e1 recebido not\u00edcias do estrangeiro!<\/p>\n\n\n\n<p><em>Al\u00f4, al\u00f4, Sr. Presidente, o Dr. seu filho voltou a empenhar o seu apelido.<\/em><\/p>\n\n\n\n<p>Embalada numa caixa digital, ostentando ins\u00edgnias de terra longe, deu \u00e0 Costa de Bel\u00e9m a (en)comenda do descendente da coroa emigrado no Brasil.<\/p>\n\n\n\n<p>Dizem as l\u00ednguas medi\u00e1ticas que a fam\u00edlia presidencial ter\u00e1, no imediato, partilhado a (en)comenda com a fam\u00edlia governativa, celebrando o ato com um pacto, corria ent\u00e3o o m\u00eas de outubro de 2019!<\/p>\n\n\n\n<p>Sem olhar a meios, a governan\u00e7a socialista habituada a resolver com celeridade assuntos de fam\u00edlia, ativou a rede de influ\u00eancias e, num \u00e1pice, encontrou forma de aviar a (en)comenda. De pronto, tudo ter\u00e1 come\u00e7ado a bulir, telefonemas, e-mails, cartas, postais de boas festas, atestados de resid\u00eancia, recibos, facturas, receitas, escrituras de apartamentos, cadeiras e andarilhos, resist\u00eancias pontuais, press\u00e3o sobre equipas m\u00e9dicas, sai <a href=\"https:\/\/www.jn.pt\/2565950214\/ex-governante-diz-que-tambem-teria-ajudado-no-caso-das-gemeas\/\">Francisco Ramos<\/a> e entra Sales na tal secretaria de estado, conhecida pela prontid\u00e3o na marca\u00e7\u00e3o de consultas para amigos do descendente da coroa.&nbsp;<\/p>\n\n\n\n<p>Ultrapassando tudo e todos, em meia-d\u00fazia de contactos o desejo do Dr. filho do Presidente Marcelo viu-se concretizado!<\/p>\n\n\n\n<p>Sem surpresa, os abusos de poder e o tr\u00e1fico de influ\u00eancias preponderaram.<\/p>\n\n\n\n<p>Do Minist\u00e9rio da Sa\u00fade \u00e0 secretaria de Estado das Comunidades, passando pelo gabinete do Infarmed, todas as portas se abriram para deixarem passar o fandango presidencial.&nbsp;<\/p>\n\n\n\n<p><strong>6. Isolamento Social&nbsp;<\/strong><\/p>\n\n\n\n<p><strong><em>A conduta negligente e abusiva dos traficantes de influ\u00eancias, que bloqueou o normal funcionamento organismos p\u00fablicos e degradou as institui\u00e7\u00f5es de Estado, provocou danos sociais irrevers\u00edveis.&nbsp;<\/em> <em>A generalidade da popula\u00e7\u00e3o foi for\u00e7ada a manter as suas dores isoladas, para evitar que se espalhasse o p\u00e2nico e fosse evidente o seu sofrimento.&nbsp;<\/em><\/strong><\/p>\n\n\n\n<p>Efetivamente, a generalidade dos utentes que, ano ap\u00f3s ano, se v\u00ea for\u00e7ada a pernoitar ao relento para se habilitar a uma vaga para consulta, tem raz\u00f5es de sobra para considerar a interven\u00e7\u00e3o das mais altas figuras de estado, na instrumentaliza\u00e7\u00e3o do Servi\u00e7o Nacional de Sa\u00fade em prol da concretiza\u00e7\u00e3o do desejo do Dr. filho do Presidente Marcelo, um miser\u00e1vel insulto \u00e0s suas dores e um insustent\u00e1vel desprezo pela equidade no acesso aos cuidados de sa\u00fade.<\/p>\n\n\n\n<p>Infelizmente, ap\u00f3s a moment\u00e2nea como\u00e7\u00e3o coletiva, insuflada pelo alarde medi\u00e1tico, nada de substancial sucedeu, o SNS continua a ser destru\u00eddo, os utentes permanecem enredados nos seus&nbsp; destro\u00e7os e oligarquia dominante est\u00e1 de boa sa\u00fade.&nbsp; As den\u00fancias bomb\u00e1sticas, as entrevistas de \u00faltima hora, os relatos atabalhoados dos principais envolvidos, n\u00e3o deixaram rastro, num \u00e1pice sa\u00edram de cena para darem lugar a outras mat\u00e9rias de alto rendimento medi\u00e1tico. Sobre a indecorosa forma como foi aviada a (en)comenda presidencial, sobram apenas memes pouco sofisticados e um rol de desorganizadas mem\u00f3rias virtuais, as quais rapidamente ser\u00e3o apagadas pelo scroll por onde escorre o tempo da generalidade da popula\u00e7\u00e3o, enquanto aguarda pela sua vez numa maca emprestada, \u00e0 porta do hospital, encerrado para emerg\u00eancias por falta de pessoal dispon\u00edvel para participar no caos em que se converteram os Servi\u00e7os P\u00fablicos de Sa\u00fade da Rep\u00fablica Portuguesa!<\/p>\n\n\n\n<p><strong>7. Quarentena&nbsp;<\/strong><\/p>\n\n\n\n<p><em><strong>Apesar da severidade dos sucessivos isolamentos, a que a popula\u00e7\u00e3o tem sido sujeita, a amplia\u00e7\u00e3o das doen\u00e7<\/strong><\/em><strong><em>as sociais<\/em><\/strong><em><strong> n\u00e3o p\u00e1ra de crescer! A gravidade das enfermidades e das debilidades instalaram, entre os indiv\u00eddu<\/strong><\/em><strong><em>os, um fatal receio, que tem <\/em><\/strong><em><strong>feito aumentar o descaso para com a dores sociais alheia<\/strong><\/em><strong><em>s!<\/em><\/strong><\/p>\n\n\n\n<p>A impunidade, de que gozam os protagonistas destes sucessivos atos de gest\u00e3o abusiva, tem provocado danos irrevers\u00edveis \u00e0 prec\u00e1ria sa\u00fade da democracia! A falta de car\u00e1cter e de integridade das figuras de Estado vai cobrindo de desonra as institui\u00e7\u00f5es, arrasando a sua credibilidade e derrubando as suas fun\u00e7\u00f5es. <\/p>\n\n\n\n<p>A ruinosa conduta, perpetrada pela oligarquia dominante, tem agudizado as assimetrias sociais, condenando \u00e0 mis\u00e9ria a generalidade dos cidad\u00e3os, \u00e0 medida que cresce a sede de poder, a gan\u00e2ncia e o a\u00e7ambarcamento de dividendos para distribuir entre amigos e fam\u00edlia!<\/p>\n\n\n\n<p>Lamentavelmente, este deplor\u00e1vel Estado de Decad\u00eancia encontra-se numa fase terminal. O diagn\u00f3stico, feito com detalhe e recurso a diversas opini\u00f5es, atesta tratar-se de um doen\u00e7a irrecuper\u00e1vel, com tend\u00eancia a bloquear todos os organismos p\u00fablicos!<\/p>\n\n\n\n<p>Por\u00e9m, e apesar de cientes das maleitas sociais, que no decurso dos \u00faltimos anos t\u00eam feito crescer, Marcelo Rebelo de Sousa e Ant\u00f3nio Costa, declinaram sempre a aplica\u00e7\u00e3o de tratamentos e profilaxias que pudessem reverter a deteriora\u00e7\u00e3o do Estado! <\/p>\n\n\n\n<p>Inebriados pela dimens\u00e3o do Imp\u00e9rio, que ergueram sobre sangue e suor alheios, o Presidente e o Primeiro-Ministro ter\u00e3o perdido a no\u00e7\u00e3o e o discernimento, pelo que, lhes ter\u00e1 escapado a doen\u00e7a viral de que padecem. <\/p>\n\n\n\n<p>Desgra\u00e7adamente, a malvadez, a inc\u00faria e a decad\u00eancia moral dos traficantes de influ\u00eancias j\u00e1 n\u00e3o surpreendem ningu\u00e9m! Sem d\u00f3 nem piedade, Marta Temido, Francisco Ramos, Diogo Serras Lopes, Lacerda Sales, Jos\u00e9 Carneiro, Berta Nunes e outros tantos membros da oligarquia socialista, ter\u00e3o cumprido <em>ipsis verbis<\/em> o gui\u00e3o urdido pelos chefes das fam\u00edlias de Bel\u00e9m e S\u00e3o Bento!&nbsp;<\/p>\n\n\n\n<p>Efectivamente, a cena p\u00fablica portuguesa est\u00e1 tomada por uma insuport\u00e1vel decad\u00eancia.<\/p>\n\n\n\n<p>A degrada\u00e7\u00e3o abateu-se sobre o miser\u00e1vel arco da governa\u00e7\u00e3o, em virtude do saque e dos acordos t\u00e1citos, praticados pelas sinistras coliga\u00e7\u00f5es e pelas direitas dilaceradas.&nbsp;<\/p>\n\n\n\n<p><strong>Ao cidad\u00e3o, utente dos servi\u00e7os p\u00fablicos, resta desmontar as patranhas e os fandangos que tomam conta das lideran\u00e7as, que a seu cargo t\u00eam fun\u00e7\u00f5es governativas, para evitar sucumbir \u00e0 decad\u00eancia que sustenta o descomunal Estado de Emerg\u00eancia em que nos encontramos!<\/strong><\/p>\n\n\n\n<p><strong>Considera\u00e7\u00f5es final\u00edssimas:  <\/strong>\u00e0 data em que se publica esta reflex\u00e3o, a decad\u00eancia das figuras de Estado est\u00e1 ao rubro!  Por suspeitas de neg\u00f3cios il\u00edcitos, os governos da na\u00e7\u00e3o colapsaram e est\u00e3o todos em modo demission\u00e1rio! <\/p>\n\n\n\n<p>Marcelo, ainda a abra\u00e7os com o fandango do Dr. seu filho, j\u00e1 dissolveu a Assembleia do Continente, a dos A\u00e7ores e est\u00e1 a ponderar como e quando dissolver a da Madeira! O Presidente da Rep\u00fablica, garantiu entretanto, que assim que terminar estas dilig\u00eancias ir\u00e1 refletir se adopta as g\u00e9meas, se deserda o filho, se emigra para o Brasil ou se continua  a comer fortimel com o Fortunato na Casa da Presid\u00eancia! <\/p>\n\n\n\n<p>Ant\u00f3nia Marques<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Almas g\u00e9meas!&nbsp; O impacto, provocado pela horrenda novela de vers\u00f5es e alocu\u00e7\u00f5es, a que a revela\u00e7\u00e3o do \u201ccaso das g\u00e9meas\u201d deu azo, ter\u00e1 toldado a compreens\u00e3o da gravidade dos factos que a todos envolve! Por\u00e9m, em nome do tanto e de tantos que, sob a batuta de uma equipa ministerial, pereceram no decurso da travessia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3563,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56,113],"tags":[],"class_list":["post-3561","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-democracia","category-estado"],"_links":{"self":[{"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/posts\/3561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/comments?post=3561"}],"version-history":[{"count":10,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/posts\/3561\/revisions"}],"predecessor-version":[{"id":3582,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/posts\/3561\/revisions\/3582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/media\/3563"}],"wp:attachment":[{"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/media?parent=3561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/categories?post=3561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/tags?post=3561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}