{"id":3916,"date":"2025-03-22T19:34:05","date_gmt":"2025-03-22T19:34:05","guid":{"rendered":"https:\/\/antoniamarques.pt\/blog\/?p=3916"},"modified":"2025-03-23T14:24:41","modified_gmt":"2025-03-23T14:24:41","slug":"a-farsa-paralamentar-do-rabal-a-lapa","status":"publish","type":"post","link":"https:\/\/antoniamarques.pt\/blog\/2025\/03\/22\/a-farsa-paralamentar-do-rabal-a-lapa\/","title":{"rendered":"A Farsa par(a)lamentar: do Rabal \u00e0 Lapa"},"content":{"rendered":"\n<p class=\"has-black-color has-text-color has-link-color wp-elements-4696673c0b51bbb846ff92f9d55698e5\">Na imagem em destaque, o press\u00e1gio anunciado pela insurg\u00eancia popular, Montenegro manchado de (sol)verde,  a 28fev2024<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-ac1cc9fd4974b16371fad12ecbba012b\">Por estes dias, o parlamento luso tem sido albergue de uma trupe de figuras pat\u00e9ticas, que se movem, sem decoro, entre o Rabal e a Lapa! Hiper-dotados em ret\u00f3rica grosseira e malabarismos verbais, estes personagens tomaram de assalto o hemiciclo, fazendo estalar (mais) uma aviltante farsa. Entre dedos em riste e m\u00edmicas burlescas, a cena p\u00fablica viu-se invadida por um turbilh\u00e3o de palavras v\u00e3s e delitos inconsequentes que lan\u00e7aram erva de pasto e bolas de golfe em todas as dire\u00e7\u00f5es.&nbsp;<\/p>\n\n\n\n<p>Deplor\u00e1vel espect\u00e1culo!<\/p>\n\n\n\n<p>No primeiro dos atos, o primeiro dos ministros surpreendeu a audi\u00eancia com uma grotesca representa\u00e7\u00e3o. Misturando factos e fic\u00e7\u00e3o, desfiou conta por conta um longo ros\u00e1rio, dizendo tudo e seu contr\u00e1rio. Clamou ser pai de um par de filhos, filho de pai, m\u00e3e e do Espinho Santo, herdeiro de propriedades, neto de gente que transfere mas n\u00e3o vende patrim\u00f3nio e marido de uma senhora com quem havia casado em comunh\u00e3o de bens aven\u00e7ados! De permeio, referindo-se ao <em>core<\/em> do<em> business<\/em> de fam\u00edlia, enumerou metros e quadrados, juntas, concelhos e freguesias, pastagens, lameiros, matos e confronta\u00e7\u00f5es, esp\u00e9cies arb\u00f3reas, cabe\u00e7as de gado e p\u00e9s de videira. Assim que terminou a fastidiosa r\u00e1bula do invent\u00e1rio, atirou-se \u00e0 anuncia\u00e7\u00e3o do dom da transpar\u00eancia, do qual se diz fiel deposit\u00e1rio, em virtude de haver revelado publicamente o segredo das receitas da fam\u00edlia!&nbsp;<\/p>\n\n\n\n<p>De peito inflado e olhar esgrouviado, na plenitude do transe encenado, usou e abusou da ladainha do pobre coitado, v\u00edtima das mais ardilosas persegui\u00e7\u00f5es e vis teorias da conspira\u00e7\u00e3o! Contra as quais retorquiu. Clamando de forma estridente. Pois que afinal a real inten\u00e7\u00e3o da fam\u00edlia seria \u00fanica e exclusivamente a de edificar uma adega duplex no Rabal \u00e0 Lapa, juntando o ber\u00e7o das crias com o liteiro <em>king size<\/em> dos progenitores, e, no melhor dos cen\u00e1rios, talvez estender a atividade ao turismo de recreio na quinta sexta-feira de cada m\u00eas, para evitar pagar 300 euros\/ noite, na <em>epic<\/em> unidade hoteleira da capital, que lhe tem servido de resid\u00eancia, apenas e s\u00f3 para evitar pernoitar no quarto sem cortinados do palacete de S\u00e3o Bento!<\/p>\n\n\n\n<p>Ap\u00f3s ter puxado de todos os gal\u00f5es rurais, de que alegou ser genu\u00edno propriet\u00e1rio, o primeiro magano, visivelmente ufanado, sacudiu a erva de pasto e as bolas de golfe, e proclamou \u201c<em>homem mais transparente n\u00e3o h\u00e1\u201d<\/em>! Pelo que, advertiu, dali em diante s\u00f3 haveria de contracenar com gal\u00e3s \u201c<em>t\u00e3o ou mais mais di\u00e1fanos do que eu\u201d<\/em>!&nbsp;<\/p>\n\n\n\n<p>Assim que o <em>homo transparentis<\/em> lan\u00e7ou o repto, a plateia aven\u00e7ada, \u00e0 direita, rejubilou, aplaudindo de p\u00e9, enquanto clamava <em>Viva, Viva, SpinumViva (Espinho Viva)<\/em>!&nbsp;<\/p>\n\n\n\n<p>Quem assistiu, <em>in loco<\/em> ou em deferido, aos aplausos e del\u00edrios da malta da alian\u00e7a, ter\u00e1 ficado com a n\u00edtida sensa\u00e7\u00e3o de que a r\u00e1bula do primeiro farsante, apesar de elementar, foi suficiente para os cativar! Consequ\u00eancia, a encanta\u00e7\u00e3o e as cenas prosaicas ter\u00e3o vindo para durar.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Perguntem aos mais velhos\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/Uk5q15-A7Io?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\">Di\u00e1logos presidenciais! &#8220;Perguntem aos mais velhos&#8221;, Pedro Brito 2\/mar\u00e7o\/25<\/figcaption><\/figure>\n\n\n\n<p>E, meu dito meu feito, ainda fita par(a)lamentar estava longe de terminar e j\u00e1 uma fila extensa de novas cenas tresloucadas, com o primeiro dos ministros ao centro, se perfilava entre o Rabal e a Lapa!&nbsp;<\/p>\n\n\n\n<p>Incapaz de separar a fic\u00e7\u00e3o empresarial da realidade de Estado, Montenegro agarrou-se \u00e0 representa\u00e7\u00e3o para salvar a narrativa do, alegado, simpl\u00f3rio neg\u00f3cio de fam\u00edlia! Incapaz de sair do papel, o <em>homo transparentis<\/em> assumiu de vez a personagem e, de pronto se lan\u00e7ou ao <em>green<\/em> para continuar a farsa! <em>Et<\/em> <em>voil\u00e1<\/em>, minutos depois da grande embrulhada, veio a p\u00fablico a par\u00f3dia, organizada pela <a href=\"https:\/\/www.ordemeconomistas.pt\/xportalv3\/noticias\/noticia.xvw?p=80061772&amp;clube-de-golfe-dos-economistas-realiza-1.-torneio-a-norte\">ordem dos economistas<\/a>, em que o primeiro magano surge engalanado, com farpelas de golfe, ao lado de tacos e violas, fazendo pand\u00e3 com os poderes econ\u00f3micos!&nbsp;<\/p>\n\n\n\n<p>Que raio ter\u00e1 passado pela cabe\u00e7a desse meliante, para se arrogar o direito de gozar, de forma t\u00e3o despudorada, com quem lhe paga o ordenado? Das duas uma, ou Montenegro perdeu a cabe\u00e7a no meio da erva de pasto ou ter\u00e1 deixado cair a \u00e9tica num buraco de golfe!<\/p>\n\n\n\n<p>Ainda assim, a indecorosa presen\u00e7a no pasto com buracos ao lado de outros caras de pau, n\u00e3o teve for\u00e7a bastante para quebrar o feiti\u00e7o que Montenegro lan\u00e7ou sobre a resignada multid\u00e3o.&nbsp;<\/p>\n\n\n\n<p>Assim sendo, <em>Seguimos em frente!<\/em><\/p>\n\n\n\n<p>ter\u00e1 dito o magano \u00e0 trupe que o acompanha na governa\u00e7\u00e3o.<\/p>\n\n\n\n<p>Num \u00e1pice, a trupe que se havia instalado no hemiciclo, tomou a televis\u00e3o.<\/p>\n\n\n\n<p>Pela hora da janta, entre um <a href=\"https:\/\/ifperfilxxi.blogspot.com\/2025\/03\/mas-que-sena-senhor-primeiro-ministro.html\">(Ant\u00f3nio) Sena<\/a> genu\u00edno e umas cenas replicadas, Montenegro, em representa\u00e7\u00e3o do grupo de sequazes, falou ao pa\u00eds sobre a sua farsa familiar. Com um <a href=\"https:\/\/www.youtube.com\/watch?v=Gqea5-hrg6I\">brilhozinho nos olhos<\/a> entoou de novo a ladainha.&nbsp;<\/p>\n\n\n\n<p><em>E o que \u00e9 que foi que ele disse? E o que \u00e9 que foi que ele disse?<\/em><\/p>\n\n\n\n<p>Disse tudo o que lhe passou pela tola, e mais um pouco, fez o quatro pintou o sete e \u00e0s duas por tr\u00eas falou de um amigo que vale milh\u00f5es! Sem perder o ritmo, cantarolou a lenga-lenga \u00e0 frente dos boys, as meninas de coro arrebatadas pelo refr\u00e3o, trautearam que quem n\u00e3o v\u00ea caras, n\u00e3o v\u00ea cora\u00e7\u00f5es! Mas, afinal <em>o que \u00e9 que foi que ele disse<\/em>? <em>O que \u00e9 que foi que ele disse<\/em>?<\/p>\n\n\n\n<p>Disse tanta baboseira e respondeu a nada. Quase a terminar, removeu a mulher do retrato empresarial, desviou os cadilhos para a conta dos filhos e, entre escusas e explica\u00e7\u00f5es vagas, amea\u00e7ou os seus detratores que, caso n\u00e3o fechassem as matracas, atiraria ao ar, num dia de ventania forte, uma opa de confian\u00e7a! Assim que terminou a leitura do salmo, pegou na papelada e abandonou a sala com os amigos, pois coisa mais preciosa no mundo n\u00e3o h\u00e1!&nbsp;<\/p>\n\n\n\n<p>Mas, afinal <em>o que \u00e9 que foi que ele disse<\/em>? <em>O que \u00e9 que foi que ele disse<\/em>?&nbsp;<\/p>\n\n\n\n<p>Disse um pouco de tudo mas com nada se comprometeu.<\/p>\n\n\n\n<p>Perante a miser\u00e1vel encena\u00e7\u00e3o, e de onde menos se esperava, surgiu a censura que haveria de for\u00e7ar Montenegro a assumir, por uma vez, a palavra aven\u00e7ada! Mas, antes de tal suceder, o comentariado subvencionado por outros amigos que valem milh\u00f5es, fez render a situa\u00e7\u00e3o. Ora porque a censura havia mordido o isco, ora porque seria in\u00fatil censurar a governa\u00e7\u00e3o, ora porque a oposi\u00e7\u00e3o estaria mais inclinada a aguardar pelo passe de m\u00e1gica do primeiro dos ministros, ora porque a governa\u00e7\u00e3o seguia em velocidade cruzeiro, pelo que n\u00e3o existia mat\u00e9ria para censurar, ora porque a empresa de fam\u00edlia escapava pelos pingos da chuva, porque o parlamento n\u00e3o estaria na disposi\u00e7\u00e3o de censurar o governo! Ora porque para encher os diretos, vale tudo, at\u00e9 atirar ao ar qualquer teoria, pois palavra pronunciada por comentador aven\u00e7ado serve apenas dar eco \u00e0 voz do dono, pelo que n\u00e3o deve ser levada a s\u00e9rio!<\/p>\n\n\n\n<p>E com o tal brilhozinho nos olhos, Montenegro continuou a actua\u00e7\u00e3o!<\/p>\n\n\n\n<p>No meio da vertigem e do pasmo medi\u00e1tico, o primeiro dos ministros aparece sentado numa cadeira de Estado, pronto a ser interrogado por uma <a href=\"https:\/\/pt.wikipedia.org\/wiki\/Sandra_Felgueiras\">ex-funcion\u00e1ria<\/a> da <a href=\"https:\/\/pt.wikipedia.org\/wiki\/Medialivre\">Cofina Media<\/a>! Puxa, Portugal \u00e9 mesmo pequenote, n\u00e3o \u00e9 que as ex-Cofinas e os quase ex-primeiros ministros passam a vida a trope\u00e7ar uns nos outros!<\/p>\n\n\n\n<p>Bom, coincid\u00eancias \u00e0 parte, certo \u00e9 que o desempenho de ambos superou as piores expectativas. O que at\u00e9 poder\u00e1 ter sido \u00f3timo para incrementar o <em>share<\/em> e as perplexidade coletivas mas, certamente, ter\u00e1 sido p\u00e9ssimo para o <a href=\"https:\/\/www.sanahotels.com\/pt\/hotel\/epic-sana-lisboa\/\">Epic hotel<\/a>, em virtude de ter sido preterido, em <em>prime time, <\/em>por um cliente de vulto! Ora, de facto, o interrogat\u00f3rio, que espremido n\u00e3o daria para encher sequer um copo de sumo, terminou como havia iniciado, todos as explica\u00e7\u00f5es foram prometidas mas, em bom rigor, nada para al\u00e9m do pre\u00e7o da di\u00e1ria, pago \u00e0 unidade hoteleira onde o primeiro dos ministros assentava os costados e a p\u00e9ssima qualidade dos aposentos da resid\u00eancia oficial, foi esclarecido!&nbsp;<\/p>\n\n\n\n<p>Do confrangedor interrogat\u00f3rio ao miser\u00e1vel debate da mo\u00e7\u00e3o de confian\u00e7a, foi um passo de pardal!&nbsp;<\/p>\n\n\n\n<p>E, da tresloucada discuss\u00e3o, em torno da confian\u00e7a que falta, ao governo cortado em fatias, foi um passe de manhosa ret\u00f3rica discursiva! Com os despojos da grande farsa na algibeira e o parlamento finalmente desmantelado, Montenegro abandonou a cena sem sair do palco, rumo \u00e0 campanha para granjear a maioria com que sempre sonhou!&nbsp;<\/p>\n\n\n\n<p>Resultado, o povo ser\u00e1 em breve contactado para se pronunciar sobre a farsa do <em>Homo Transparentis<\/em>, ajuizando, pelo voto, se o personagem tem ou n\u00e3o direito de acumular a gest\u00e3o da casa de pasto da fam\u00edlia, com o desempenho do cargo de primeiro dos ministros da governa\u00e7\u00e3o da rep\u00fablica portuguesa! Tudo isto, apenas e s\u00f3, porque ao Montenegro, empres\u00e1rio, faltou \u00e9tica e decoro para evitar embrulhar a democracia em papel timbrado com as ins\u00edgnias dos imp\u00e9rios econ\u00f3micos aos quais, Montenegro, o primeiro ministro, garante a confidencialidade de dados!<\/p>\n\n\n\n<p>Por\u00e9m, asseguram os especialistas, que t\u00eam lugar cativo na bancada medi\u00e1tica, n\u00e3o \u00e9 a balb\u00fardia par(a)lamentar, nem a usura, nem a falta de lisura, t\u00e3o pouco a crescente promiscuidade dos eleitos, habituados a exercerem fun\u00e7\u00f5es no intervalo dos seus neg\u00f3cios, que nos devem preocupar. N\u00e3o, de todo, o que \u00e9 mesmo, mesmo muito grave para a democracia (deles) e para a credibilidade das institui\u00e7\u00f5es (por eles confiscadas) \u00e9 atirar o povo para novas elei\u00e7\u00f5es.<\/p>\n\n\n\n<p>De facto, a existir alguma solu\u00e7\u00e3o para debelar, ainda que pela rama, o presente Estado de s\u00edtio e evitar a queda da democracia num buraco de golfe, ela teria passado pela imediata ren\u00fancia de Montenegro ao cargo, que o voto do povo lhe confiou!&nbsp;<\/p>\n\n\n\n<p>Mas, n\u00e3o, longe de equacionar essa possibilidade, o personagem aven\u00e7ado ter\u00e1 considerado que o melhor, para salvar a farsa, seria convidar o povo a integrar o elenco da Spinumviva, ainda que tal contribu\u00edsse para violentar (ainda mais) a democracia!<\/p>\n\n\n\n<p>Resultado, ao inv\u00e9s de deixar o cargo da governa\u00e7\u00e3o, Montenegro optou por dar continuidade ao enredo da ren\u00fancia \u00e0 fam\u00edlia, na esperan\u00e7a que a lama, que importou do Rabal, seja suficiente para&nbsp; entreter o p\u00fablico e alcan\u00e7ar uma maioria parlamentar, para dedicar \u00e0 clientela da Spinumviva!<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-258519c5c9e4ac9517536d4eae36d14c\">Ora, caso viv\u00eassemos numa real e participada democracia, livre de amarras, hierarquias e assimetrias sociais, esta desfa\u00e7atez, que n\u00e3o lembraria sequer ao Diabo, seria ofensa bastante para despertar uma robusta insurg\u00eancia popular. Mas, como o regime em que vivemos est\u00e1 longe dessa idealiza\u00e7\u00e3o, restar\u00e1 ao povo enfiar as galochas para evitar derrapar no loda\u00e7al. Pois, a julgar pela intensidade da farsa, tudo leva a crer que a tempestade Montenegro, seja qual for o desfecho, continuar\u00e1 a ter efeitos devastadores.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-c1c4b8813b618d3a18c356749b1a8376\">Ant\u00f3nia Marques<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-9ac00cf961d1ea846fe5a532228b76c6\"><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ora, caso viv\u00eassemos numa real e participada democracia, livre de amarras, hierarquias e assimetrias sociais, esta desfa\u00e7atez, que n\u00e3o lembraria sequer ao Diabo, seria ofensa bastante para despertar uma robusta insurg\u00eancia popular. Mas, como o regime em que vivemos est\u00e1 longe dessa idealiza\u00e7\u00e3o, resta ao povo enfiar as galochas para evitar derrapar no loda\u00e7al. Pois, a julgar pela intensidade da farsa, tudo leva a crer que a tempestade Montenegro ter\u00e1 efeitos devastadores.<\/p>\n","protected":false},"author":2,"featured_media":3933,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[158,156,157,155],"class_list":["post-3916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-democracia","tag-democracia-participativa","tag-eleicoes","tag-montenegro","tag-spinumviva"],"_links":{"self":[{"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/posts\/3916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/comments?post=3916"}],"version-history":[{"count":9,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/posts\/3916\/revisions"}],"predecessor-version":[{"id":3932,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/posts\/3916\/revisions\/3932"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/media\/3933"}],"wp:attachment":[{"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/media?parent=3916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/categories?post=3916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/antoniamarques.pt\/blog\/wp-json\/wp\/v2\/tags?post=3916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}